{"id":3049,"date":"2024-10-24T05:50:51","date_gmt":"2024-10-24T05:50:51","guid":{"rendered":"https:\/\/marmodxb.org\/?page_id=3049"},"modified":"2024-11-07T09:55:25","modified_gmt":"2024-11-07T09:55:25","slug":"granite","status":"publish","type":"page","link":"https:\/\/marmodxb.org\/en\/granite\/","title":{"rendered":"GRANITE"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3049\" class=\"elementor elementor-3049\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2368735 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2368735\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d291e3b\" data-id=\"7d291e3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-147ac28c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"147ac28c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3cf87062\" data-id=\"3cf87062\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7092aec elementor-widget elementor-widget-heading\" data-id=\"7092aec\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">GRANITE<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f96396 elementor-widget elementor-widget-text-editor\" data-id=\"3f96396\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Granite has been in use for millennia as a symbol of power, endurance, and durability. Although granite has been most widely used for countertops, flooring, and bathrooms, it exotic granites may be used in several other areas of the residence to draw the awestruck eyes of your guests.<\/p><p><a href=\"https:\/\/www.rkmarble.com\/the-different-uses-of-granite-at-home\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Granite\u00a0<\/strong><\/a>\u00a0can also be used in landscape gardens to design classic masterpieces and truly unique decorative elements. The best thing about imported granite is that its maintenance is relatively simple if managed carefully. Using granite for house interior decoration is a very suitable way to spruce up the residence.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53d6978 elementor-widget elementor-widget-image\" data-id=\"53d6978\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/marmodxb.org\/wp-content\/uploads\/2024\/10\/granite-pic-1.webp\" class=\"attachment-full size-full wp-image-2800\" alt=\"\" srcset=\"https:\/\/marmodxb.org\/wp-content\/uploads\/2024\/10\/granite-pic-1.webp 1024w, https:\/\/marmodxb.org\/wp-content\/uploads\/2024\/10\/granite-pic-1-300x200.webp 300w, https:\/\/marmodxb.org\/wp-content\/uploads\/2024\/10\/granite-pic-1-768x512.webp 768w, https:\/\/marmodxb.org\/wp-content\/uploads\/2024\/10\/granite-pic-1-600x400.webp 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-714b0f4 elementor-widget elementor-widget-heading\" data-id=\"714b0f4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">How Granite is Produced<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0554305 elementor-widget elementor-widget-text-editor\" data-id=\"0554305\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Granite is formed deep within the Earth\u2019s crust through the slow crystallization of magma, creating a dense and incredibly strong stone. The stone is extracted from quarries using advanced cutting technology, often in countries known for high-quality granite production such as Brazil, India, China, Italy, and the United States. After extraction, large blocks of granite are cut into slabs or tiles and polished to reveal their natural beauty. The result is a strong, visually striking material that\u2019s ready to be transformed into countertops, flooring, wall cladding, and more.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-773749d elementor-widget elementor-widget-image\" data-id=\"773749d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/marmodxb.org\/wp-content\/uploads\/2024\/09\/GRANITE-PIC-2.jpeg\" class=\"attachment-full size-full wp-image-2386\" alt=\"\" srcset=\"https:\/\/marmodxb.org\/wp-content\/uploads\/2024\/09\/GRANITE-PIC-2.jpeg 1500w, https:\/\/marmodxb.org\/wp-content\/uploads\/2024\/09\/GRANITE-PIC-2-300x200.jpeg 300w, https:\/\/marmodxb.org\/wp-content\/uploads\/2024\/09\/GRANITE-PIC-2-1024x683.jpeg 1024w, https:\/\/marmodxb.org\/wp-content\/uploads\/2024\/09\/GRANITE-PIC-2-768x512.jpeg 768w, https:\/\/marmodxb.org\/wp-content\/uploads\/2024\/09\/GRANITE-PIC-2-600x400.jpeg 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d21528 elementor-widget elementor-widget-heading\" data-id=\"0d21528\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Where Can Granite Be Used?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c9e852 elementor-widget elementor-widget-text-editor\" data-id=\"6c9e852\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Thanks to its durability and beauty, granite is a versatile material suitable for a variety of interior applications:<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b4f6e4 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7b4f6e4\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/marmodxb.org\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kitchen Countertops<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bathroom Vanities<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Flooring<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fireplace Surrounds<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Feature Walls & Cladding<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Staircases<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>GRANITE Granite has been in use for millennia as a symbol of power, endurance, and durability. Although granite has been&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3049","page","type-page","status-publish","hentry"],"post-meta":{"_edit_lock":["1730973327:2"],"_edit_last":["2"],"site-container":["default"],"site-header-transparent":["default"],"site-page-header":["default"],"site-sidebar":["default"],"_elementor_edit_mode":["builder"],"_elementor_template_type":["wp-page"],"_elementor_version":["3.23.4"],"_wp_page_template":["default"],"_elementor_data":["[{\"id\":\"2368735\",\"elType\":\"section\",\"settings\":{\"content_width\":{\"unit\":\"px\",\"size\":700},\"background_position\":\"center center\",\"background_attachment\":\"fixed\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_background\":\"classic\",\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":0.97},\"padding\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"50\",\"left\":\"0\",\"isLinked\":false},\"custom_height\":{\"unit\":\"vh\",\"size\":75},\"gap\":\"wide\",\"content_position\":\"middle\",\"padding_mobile\":{\"unit\":\"px\",\"top\":\"40\",\"right\":\"0\",\"bottom\":\"40\",\"left\":\"0\",\"isLinked\":false},\"text_align\":\"center\",\"layout\":\"full_width\",\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"0\",\"bottom\":\"30\",\"left\":\"0\",\"isLinked\":false},\"background_image\":{\"url\":\"https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/ONYX-PIC-1.webp\",\"id\":2804,\"size\":\"\",\"alt\":\"\",\"source\":\"library\"}},\"elements\":[{\"id\":\"7d291e3b\",\"elType\":\"column\",\"settings\":{\"_column_size\":100,\"_inline_size\":null,\"space_between_widgets\":12,\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"147ac28c\",\"elType\":\"section\",\"settings\":{\"padding\":{\"unit\":\"em\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"layout\":\"full_width\"},\"elements\":[{\"id\":\"3cf87062\",\"elType\":\"column\",\"settings\":{\"_column_size\":100,\"_inline_size\":null},\"elements\":[{\"id\":\"7092aec\",\"elType\":\"widget\",\"settings\":{\"title\":\"GRANITE\",\"align\":\"left\",\"typography_typography\":\"custom\",\"typography_font_size\":{\"unit\":\"px\",\"size\":20,\"sizes\":[]},\"typography_font_size_mobile\":{\"unit\":\"px\",\"size\":18,\"sizes\":[]},\"typography_font_weight\":\"600\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"3f96396\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<p>Granite has been in use for millennia as a symbol of power, endurance, and durability. Although granite has been most widely used for countertops, flooring, and bathrooms, it exotic granites may be used in several other areas of the residence to draw the awestruck eyes of your guests.<\\\/p><p><a href=\\\"https:\\\/\\\/www.rkmarble.com\\\/the-different-uses-of-granite-at-home\\\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\"><strong>Granite\\u00a0<\\\/strong><\\\/a>\\u00a0can also be used in landscape gardens to design classic masterpieces and truly unique decorative elements. The best thing about imported granite is that its maintenance is relatively simple if managed carefully. Using granite for house interior decoration is a very suitable way to spruce up the residence.<\\\/p>\",\"align\":\"left\",\"text_color\":\"#505050\",\"typography_typography\":\"custom\"},\"elements\":[],\"widgetType\":\"text-editor\"},{\"id\":\"53d6978\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/granite-pic-1.webp\",\"id\":2800,\"size\":\"\",\"alt\":\"\",\"source\":\"library\"},\"image_size\":\"full\",\"align\":\"left\",\"width\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]}},\"elements\":[],\"widgetType\":\"image\"},{\"id\":\"714b0f4\",\"elType\":\"widget\",\"settings\":{\"title\":\"How Granite is Produced\",\"align\":\"left\",\"typography_typography\":\"custom\",\"typography_font_size\":{\"unit\":\"px\",\"size\":30,\"sizes\":[]},\"typography_font_size_mobile\":{\"unit\":\"px\",\"size\":22,\"sizes\":[]},\"typography_font_weight\":\"500\",\"typography_line_height_tablet\":{\"unit\":\"em\",\"size\":1.4,\"sizes\":[]},\"_margin\":{\"unit\":\"px\",\"top\":\"20\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"20\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"0554305\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<p>Granite is formed deep within the Earth\\u2019s crust through the slow crystallization of magma, creating a dense and incredibly strong stone. The stone is extracted from quarries using advanced cutting technology, often in countries known for high-quality granite production such as Brazil, India, China, Italy, and the United States. After extraction, large blocks of granite are cut into slabs or tiles and polished to reveal their natural beauty. The result is a strong, visually striking material that\\u2019s ready to be transformed into countertops, flooring, wall cladding, and more.<\\\/p>\",\"align\":\"left\",\"text_color\":\"#505050\",\"typography_typography\":\"custom\",\"_margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"-10\",\"left\":\"0\",\"isLinked\":false},\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"},{\"id\":\"773749d\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/GRANITE-PIC-2.jpeg\",\"id\":2386,\"size\":\"\",\"alt\":\"\",\"source\":\"library\"},\"image_size\":\"full\",\"align\":\"left\",\"width\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]}},\"elements\":[],\"widgetType\":\"image\"},{\"id\":\"0d21528\",\"elType\":\"widget\",\"settings\":{\"title\":\"Where Can Granite Be Used?\",\"align\":\"left\",\"typography_typography\":\"custom\",\"typography_font_size\":{\"unit\":\"px\",\"size\":30,\"sizes\":[]},\"typography_font_size_mobile\":{\"unit\":\"px\",\"size\":22,\"sizes\":[]},\"typography_font_weight\":\"500\",\"typography_line_height_tablet\":{\"unit\":\"em\",\"size\":1.4,\"sizes\":[]},\"_margin\":{\"unit\":\"px\",\"top\":\"20\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"20\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"6c9e852\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<p>Thanks to its durability and beauty, granite is a versatile material suitable for a variety of interior applications:<\\\/p>\",\"align\":\"left\",\"text_color\":\"#505050\",\"typography_typography\":\"custom\",\"_margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"-10\",\"left\":\"0\",\"isLinked\":false},\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"},{\"id\":\"7b4f6e4\",\"elType\":\"widget\",\"settings\":{\"icon_list\":[{\"text\":\"Kitchen Countertops\",\"_id\":\"8fadbd5\",\"selected_icon\":{\"value\":\"\",\"library\":\"\"}},{\"text\":\"Bathroom Vanities\",\"_id\":\"d90e834\",\"selected_icon\":{\"value\":\"\",\"library\":\"\"}},{\"text\":\"Flooring\",\"_id\":\"69f2a3a\",\"selected_icon\":{\"value\":\"\",\"library\":\"\"}},{\"text\":\"Fireplace Surrounds\",\"_id\":\"c896a0f\",\"selected_icon\":{\"value\":\"\",\"library\":\"\"}},{\"text\":\"Feature Walls & Cladding\",\"_id\":\"fcae1dd\",\"selected_icon\":{\"value\":\"\",\"library\":\"\"}},{\"text\":\"Staircases\",\"_id\":\"2374769\",\"selected_icon\":{\"value\":\"\",\"library\":\"\"}}],\"space_between\":{\"unit\":\"px\",\"size\":10,\"sizes\":[]},\"__globals__\":{\"icon_color\":\"globals\\\/colors?id=c44dea5\",\"text_color\":\"globals\\\/colors?id=secondary\"}},\"elements\":[],\"widgetType\":\"icon-list\"}],\"isInner\":true}],\"isInner\":true}],\"isInner\":false}],\"isInner\":false}]"],"_elementor_page_assets":["a:0:{}"],"_elementor_css":["a:6:{s:4:\"time\";i:1777498568;s:5:\"fonts\";a:0:{}s:5:\"icons\";a:1:{i:0;s:0:\"\";}s:20:\"dynamic_elements_ids\";a:0:{}s:6:\"status\";s:4:\"file\";i:0;s:0:\"\";}"],"_elementor_element_cache":["{\"timeout\":1778790546,\"value\":{\"content\":\"\\t\\t<section class=\\\"elementor-section elementor-top-section elementor-element elementor-element-2368735 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\\\" data-id=\\\"2368735\\\" data-element_type=\\\"section\\\">\\n\\t\\t\\t\\t\\t\\t\\t<div class=\\\"elementor-background-overlay\\\"><\\\/div>\\n\\t\\t\\t\\t\\t\\t\\t<div class=\\\"elementor-container elementor-column-gap-wide\\\">\\n\\t\\t\\t\\t\\t<div class=\\\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d291e3b\\\" data-id=\\\"7d291e3b\\\" data-element_type=\\\"column\\\">\\n\\t\\t\\t<div class=\\\"elementor-widget-wrap elementor-element-populated\\\">\\n\\t\\t\\t\\t\\t\\t<section class=\\\"elementor-section elementor-inner-section elementor-element elementor-element-147ac28c elementor-section-full_width elementor-section-height-default elementor-section-height-default\\\" data-id=\\\"147ac28c\\\" data-element_type=\\\"section\\\">\\n\\t\\t\\t\\t\\t\\t<div class=\\\"elementor-container elementor-column-gap-default\\\">\\n\\t\\t\\t\\t\\t<div class=\\\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3cf87062\\\" data-id=\\\"3cf87062\\\" data-element_type=\\\"column\\\">\\n\\t\\t\\t<div class=\\\"elementor-widget-wrap elementor-element-populated\\\">\\n\\t\\t\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-7092aec elementor-widget elementor-widget-heading\\\" data-id=\\\"7092aec\\\" data-element_type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t<style>\\\/*! elementor - v3.23.0 - 05-08-2024 *\\\/\\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\\\/style><h2 class=\\\"elementor-heading-title elementor-size-default\\\">GRANITE<\\\/h2>\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-3f96396 elementor-widget elementor-widget-text-editor\\\" data-id=\\\"3f96396\\\" data-element_type=\\\"widget\\\" data-widget_type=\\\"text-editor.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t<style>\\\/*! elementor - v3.23.0 - 05-08-2024 *\\\/\\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\\\/style>\\t\\t\\t\\t<p>Granite has been in use for millennia as a symbol of power, endurance, and durability. Although granite has been most widely used for countertops, flooring, and bathrooms, it exotic granites may be used in several other areas of the residence to draw the awestruck eyes of your guests.<\\\/p><p><a href=\\\"https:\\\/\\\/www.rkmarble.com\\\/the-different-uses-of-granite-at-home\\\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\"><strong>Granite\\u00a0<\\\/strong><\\\/a>\\u00a0can also be used in landscape gardens to design classic masterpieces and truly unique decorative elements. The best thing about imported granite is that its maintenance is relatively simple if managed carefully. Using granite for house interior decoration is a very suitable way to spruce up the residence.<\\\/p>\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-53d6978 elementor-widget elementor-widget-image\\\" data-id=\\\"53d6978\\\" data-element_type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t<style>\\\/*! elementor - v3.23.0 - 05-08-2024 *\\\/\\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\\\".svg\\\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\\\/style>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"1024\\\" height=\\\"683\\\" src=\\\"https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/granite-pic-1.webp\\\" class=\\\"attachment-full size-full wp-image-2800\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/granite-pic-1.webp 1024w, https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/granite-pic-1-300x200.webp 300w, https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/granite-pic-1-768x512.webp 768w, https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/granite-pic-1-600x400.webp 600w\\\" sizes=\\\"(max-width: 1024px) 100vw, 1024px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-714b0f4 elementor-widget elementor-widget-heading\\\" data-id=\\\"714b0f4\\\" data-element_type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t<h2 class=\\\"elementor-heading-title elementor-size-default\\\">How Granite is Produced<\\\/h2>\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-0554305 elementor-widget elementor-widget-text-editor\\\" data-id=\\\"0554305\\\" data-element_type=\\\"widget\\\" data-widget_type=\\\"text-editor.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t<p>Granite is formed deep within the Earth\\u2019s crust through the slow crystallization of magma, creating a dense and incredibly strong stone. The stone is extracted from quarries using advanced cutting technology, often in countries known for high-quality granite production such as Brazil, India, China, Italy, and the United States. After extraction, large blocks of granite are cut into slabs or tiles and polished to reveal their natural beauty. The result is a strong, visually striking material that\\u2019s ready to be transformed into countertops, flooring, wall cladding, and more.<\\\/p>\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-773749d elementor-widget elementor-widget-image\\\" data-id=\\\"773749d\\\" data-element_type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"1500\\\" height=\\\"1000\\\" src=\\\"https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/GRANITE-PIC-2.jpeg\\\" class=\\\"attachment-full size-full wp-image-2386\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/GRANITE-PIC-2.jpeg 1500w, https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/GRANITE-PIC-2-300x200.jpeg 300w, https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/GRANITE-PIC-2-1024x683.jpeg 1024w, https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/GRANITE-PIC-2-768x512.jpeg 768w, https:\\\/\\\/marmodxb.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/GRANITE-PIC-2-600x400.jpeg 600w\\\" sizes=\\\"(max-width: 1500px) 100vw, 1500px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-0d21528 elementor-widget elementor-widget-heading\\\" data-id=\\\"0d21528\\\" data-element_type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t<h2 class=\\\"elementor-heading-title elementor-size-default\\\">Where Can Granite Be Used?<\\\/h2>\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-6c9e852 elementor-widget elementor-widget-text-editor\\\" data-id=\\\"6c9e852\\\" data-element_type=\\\"widget\\\" data-widget_type=\\\"text-editor.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t<p>Thanks to its durability and beauty, granite is a versatile material suitable for a variety of interior applications:<\\\/p>\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-7b4f6e4 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\\\" data-id=\\\"7b4f6e4\\\" data-element_type=\\\"widget\\\" data-widget_type=\\\"icon-list.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t<link rel=\\\"stylesheet\\\" href=\\\"https:\\\/\\\/marmodxb.org\\\/wp-content\\\/plugins\\\/elementor\\\/assets\\\/css\\\/widget-icon-list.min.css\\\">\\t\\t<ul class=\\\"elementor-icon-list-items\\\">\\n\\t\\t\\t\\t\\t\\t\\t<li class=\\\"elementor-icon-list-item\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<span class=\\\"elementor-icon-list-text\\\">Kitchen Countertops<\\\/span>\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/li>\\n\\t\\t\\t\\t\\t\\t\\t\\t<li class=\\\"elementor-icon-list-item\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<span class=\\\"elementor-icon-list-text\\\">Bathroom Vanities<\\\/span>\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/li>\\n\\t\\t\\t\\t\\t\\t\\t\\t<li class=\\\"elementor-icon-list-item\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<span class=\\\"elementor-icon-list-text\\\">Flooring<\\\/span>\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/li>\\n\\t\\t\\t\\t\\t\\t\\t\\t<li class=\\\"elementor-icon-list-item\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<span class=\\\"elementor-icon-list-text\\\">Fireplace Surrounds<\\\/span>\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/li>\\n\\t\\t\\t\\t\\t\\t\\t\\t<li class=\\\"elementor-icon-list-item\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<span class=\\\"elementor-icon-list-text\\\">Feature Walls & Cladding<\\\/span>\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/li>\\n\\t\\t\\t\\t\\t\\t\\t\\t<li class=\\\"elementor-icon-list-item\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<span class=\\\"elementor-icon-list-text\\\">Staircases<\\\/span>\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/li>\\n\\t\\t\\t\\t\\t\\t<\\\/ul>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t<\\\/section>\\n\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t<\\\/section>\\n\\t\\t\",\"scripts\":[],\"styles\":[]}}"]},"_links":{"self":[{"href":"https:\/\/marmodxb.org\/en\/wp-json\/wp\/v2\/pages\/3049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marmodxb.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/marmodxb.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/marmodxb.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marmodxb.org\/en\/wp-json\/wp\/v2\/comments?post=3049"}],"version-history":[{"count":7,"href":"https:\/\/marmodxb.org\/en\/wp-json\/wp\/v2\/pages\/3049\/revisions"}],"predecessor-version":[{"id":3392,"href":"https:\/\/marmodxb.org\/en\/wp-json\/wp\/v2\/pages\/3049\/revisions\/3392"}],"wp:attachment":[{"href":"https:\/\/marmodxb.org\/en\/wp-json\/wp\/v2\/media?parent=3049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}